{"id":11197,"date":"2025-03-24T21:44:01","date_gmt":"2025-03-24T21:44:01","guid":{"rendered":"https:\/\/ineditinnova.com\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/"},"modified":"2025-03-24T22:01:42","modified_gmt":"2025-03-24T22:01:42","slug":"models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd","status":"publish","type":"post","link":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/","title":{"rendered":"Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD)"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">El sector de la construcci\u00f3n es el que m\u00e1s residuos genera: el 40% de los residuos en Europa y el 29,8% en Espa\u00f1a. En Catalu\u00f1a, en 2023 se generaron m\u00e1s de siete millones de toneladas de residuos. Estos incluyen materiales como hormig\u00f3n, ladrillos, yeso, madera, vidrio, metales, pl\u00e1stico, disolventes, amianto y tierras excavadas, y la mayor\u00eda acaban en vertederos o son incinerados. Por ello, <strong>es necesario encontrar soluciones innovadoras para minimizar y fomentar la reutilizaci\u00f3n y el reciclaje de los residuos de construcci\u00f3n y demolici\u00f3n (RCD)<\/strong>. La soluci\u00f3n pasa por impulsar modelos de negocio circulares dentro del sector, y c\u00f3mo hacerlo es el reto al que dar\u00e1 respuesta el proyecto <strong>\u00abAn\u00e1lisis de nuevos modelos de negocio circulares en torno a los RCD y validaci\u00f3n a trav\u00e9s de una fase de experimentaci\u00f3n en obra\u00bb<\/strong>, impulsado por el <a href=\"https:\/\/www.crec.cat\/\">Cl\u00faster de Residuos de Catalunya (CREC)<\/a>, y con la participaci\u00f3n de in\u00e8dit.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>in\u00e8dit dise\u00f1ar\u00e1 y dinamizar\u00e1 dos talleres participativos con agentes clave del sector, del que saldr\u00e1n posibles modelos de negocio circulares<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">Dentro del proyecto, in\u00e8dit es responsable de dise\u00f1ar y dinamizar dos talleres participativos con agentes clave del sector, de los que surgir\u00e1n propuestas de posibles modelos de negocio circulares, que tambi\u00e9n se validar\u00e1n. Por otro lado, junto con <a href=\"https:\/\/ecointelligentgrowth.net\/\">Eco Intelligent Growth<\/a>, dise\u00f1ar\u00e1n la fase experimental del proyecto, en la que se probar\u00e1n, validar\u00e1n y analizar\u00e1n en obras reales algunas de las estrategias o modelos de negocio circulares que se hayan propuesto y definido en los talleres participativos. En la fase experimental tambi\u00e9n est\u00e1 implicado el <a href=\"https:\/\/calafgrup.com\/ca\/\">Calaf Grup<\/a>, que liderar\u00e1 la ejecuci\u00f3n de la fase de experimentaci\u00f3n en obra.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>El proyecto incluye una fase experimental, en la que se probar\u00e1n, validar\u00e1n y analizar\u00e1n en obras reales algunas de las estrategias o modelos de negocio circulares que se hayan propuesto y definido en los talleres participativos<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">Con estos nuevos modelos de negocio circulares, <strong>se pretende explorar v\u00edas para valorizar estos residuos, ya sea transform\u00e1ndolos en nuevos materiales de construcci\u00f3n reciclados o fomentando los canales comerciales que faciliten su reutilizaci\u00f3n. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">En el proyecto est\u00e1n implicados diversos agentes clave del ecosistema del sector de la construcci\u00f3n en Catalu\u00f1a, como proveedores de materiales y productos, empresas constructoras, centros de conocimiento e innovaci\u00f3n, gestores de residuos o la Administraci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El objetivo final: ser el est\u00edmulo de nuevas iniciativas circulares<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-src=\"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/taller-crec-residus-construccio-1024x576.jpg\" alt=\"\" class=\"wp-image-11192 lazyload\" data-srcset=\"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/taller-crec-residus-construccio-1024x576.jpg 1024w, https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/taller-crec-residus-construccio-300x169.jpg 300w, https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/taller-crec-residus-construccio-768x432.jpg 768w, https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/taller-crec-residus-construccio.jpg 1273w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/576;\" \/><figcaption class=\"wp-element-caption\">Primero de los talleres de co-creaci\u00f3n, dinamizado por Elena Badia Elias y Adriana Sanz Mirabal<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">En la primera fase del proyecto, <strong>se realiz\u00f3 un diagn\u00f3stico del sector de los residuos de construcci\u00f3n y demolici\u00f3n. <\/strong>En febrero se celebr\u00f3 un primer taller de cocreaci\u00f3n dinamizado por <strong>Elena Badia Elias <\/strong>y <strong>Adriana Sanz Mirabal<\/strong>, responsables de proyectos de in\u00e8dit, en el que se revisaron buenas pr\u00e1cticas en torno a los flujos de RCD y se identificaron potenciales iniciativas a activar para desarrollar modelos de negocio circulares que los valoricen como recurso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">Algunas de las reflexiones clave que surgieron de este primer taller fueron:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li style=\"font-size:25px\">&#8211; <strong>Los residuos que est\u00e1n bien segregados y caracterizados en origen podr\u00e1n recuperarse m\u00e1s f\u00e1cilmente.<\/strong><\/li>\n\n\n\n<li style=\"font-size:25px\">&#8211; Es necesario <strong>identificar las palancas econ\u00f3micas que impulsen la transformaci\u00f3n de la industria e incentiven la demanda de materiales recuperados.<\/strong><\/li>\n\n\n\n<li style=\"font-size:25px\">&#8211; Para implementar iniciativas circulares en el sector, <strong>es fundamental conocer el ecosistema de actores e identificar aquellos agentes de la cadena de valor<\/strong> que son receptivos y proactivos en materia de circularidad.<\/li>\n\n\n\n<li style=\"font-size:25px\">&#8211; Existe un <strong>gran desconocimiento <\/strong>y <strong>poca fiscalizaci\u00f3n <\/strong>de las obligaciones legales del sector en materia de circularidad.<\/li>\n\n\n\n<li style=\"font-size:25px\">&#8211; Para que el sector sea m\u00e1s circular, <strong>la Administraci\u00f3n debe posicionarse como facilitadora del cambio.<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">El 1 de abril se celebrar\u00e1 un segundo taller, tambi\u00e9n dinamizado por in\u00e8dit, en el que se profundizar\u00e1 sobre c\u00f3mo pilotar algunas de las iniciativas propuestas en el primer taller y que servir\u00e1 de base para dise\u00f1ar la fase experimental del proyecto. \u00abLa idea de la prueba piloto es que, una vez finalizado el proyecto, esta se perpet\u00fae y mejore con el tiempo, y que, en el mejor de los casos, <strong>sirva como est\u00edmulo para poner en marcha otras iniciativas o modelos de negocio circulares\u00bb, afirman Elias y Sanz.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">\u00abAn\u00e1lisis de nuevos modelos de negocio circulares en torno a los RCD y validaci\u00f3n a trav\u00e9s de una fase de experimentaci\u00f3n en obra\u00bb est\u00e1 coordinado por el Cl\u00faster de Residuos de Catalu\u00f1a (CREC) y, adem\u00e1s de in\u00e8dit, participan Eco Intelligent Growth y el <a href=\"https:\/\/ecocgm.com\/\">Centre de Gesti\u00f3 Mediambiental (CGM)<\/a>; colaboran en el proyecto <a href=\"https:\/\/www.celsagroup.com\/\">CELSA GROUP<\/a>, <a href=\"https:\/\/alier.com\/ca\/\">ALIER<\/a>, <a href=\"https:\/\/www.blueroominnovation.com\/ca\/\">Blue Room Innovation<\/a> y <a href=\"https:\/\/www.theker.eu\/\">THEKER Robotics<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">El proyecto se inici\u00f3 el 15 de enero y est\u00e1 previsto que finalice en agosto. Cuenta con un presupuesto de 99.754,75 euros y est\u00e1 financiado por la convocatoria de proyectos IRC de ACCI\u00d3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector de la construcci\u00f3n es el que m\u00e1s residuos genera: el 40% de los residuos en Europa y el 29,8% en Espa\u00f1a. En Catalu\u00f1a, en 2023 se generaron m\u00e1s de siete millones de toneladas de residuos. Estos incluyen materiales como hormig\u00f3n, ladrillos, yeso, madera, vidrio, metales, pl\u00e1stico, disolventes, amianto y tierras excavadas, y la&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/\" title=\"Read Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD)\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":11191,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[31],"tags":[54],"class_list":["post-11197","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cadena","tag-noticia-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD) - in\u00e8dit<\/title>\n<meta name=\"description\" content=\"El sector de la construcci\u00f3n es el que m\u00e1s residuos genera: el 40% de los residuos en Europa y el 29,8% en Espa\u00f1a. En Catalu\u00f1a, en 2023 se generaron m\u00e1s de siete millones de toneladas de residuos. Estos incluyen materiales como hormig\u00f3n, ladrillos, yeso, madera, vidrio, metales, pl\u00e1stico, disolventes, amianto y tierras excavadas, y la mayor\u00eda acaban en vertederos o son incinerados. Por ello, es necesario encontrar soluciones innovadoras para minimizar y fomentar la reutilizaci\u00f3n y el reciclaje de los residuos de construcci\u00f3n y demolici\u00f3n (RCD). La soluci\u00f3n pasa por impulsar modelos de negocio circulares dentro del sector, y c\u00f3mo hacerlo es el reto al que dar\u00e1 respuesta el proyecto \u00abAn\u00e1lisis de nuevos modelos de negocio circulares en torno a los RCD y validaci\u00f3n a trav\u00e9s de una fase de experimentaci\u00f3n en obra\u00bb, impulsado por el Cl\u00faster de Residuos de Catalu\u00f1a (CREC), y con la participaci\u00f3n de in\u00e8dit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD) - in\u00e8dit\" \/>\n<meta property=\"og:description\" content=\"El sector de la construcci\u00f3n es el que m\u00e1s residuos genera: el 40% de los residuos en Europa y el 29,8% en Espa\u00f1a. En Catalu\u00f1a, en 2023 se generaron m\u00e1s de siete millones de toneladas de residuos. Estos incluyen materiales como hormig\u00f3n, ladrillos, yeso, madera, vidrio, metales, pl\u00e1stico, disolventes, amianto y tierras excavadas, y la mayor\u00eda acaban en vertederos o son incinerados. Por ello, es necesario encontrar soluciones innovadoras para minimizar y fomentar la reutilizaci\u00f3n y el reciclaje de los residuos de construcci\u00f3n y demolici\u00f3n (RCD). La soluci\u00f3n pasa por impulsar modelos de negocio circulares dentro del sector, y c\u00f3mo hacerlo es el reto al que dar\u00e1 respuesta el proyecto \u00abAn\u00e1lisis de nuevos modelos de negocio circulares en torno a los RCD y validaci\u00f3n a trav\u00e9s de una fase de experimentaci\u00f3n en obra\u00bb, impulsado por el Cl\u00faster de Residuos de Catalu\u00f1a (CREC), y con la participaci\u00f3n de in\u00e8dit.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/\" \/>\n<meta property=\"og:site_name\" content=\"in\u00e8dit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ineditinnovacio\/?ref=page_internal\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-24T21:44:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-24T22:01:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/residus_construccio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Codina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ineditinnova\" \/>\n<meta name=\"twitter:site\" content=\"@ineditinnova\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Codina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/\"},\"author\":{\"name\":\"Codina\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\"},\"headline\":\"Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD)\",\"datePublished\":\"2025-03-24T21:44:01+00:00\",\"dateModified\":\"2025-03-24T22:01:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/\"},\"wordCount\":859,\"image\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/residus_construccio.jpg\",\"keywords\":[\"NOTICIA\"],\"articleSection\":[\"ESTRATEGIA DE NEGOCIO SOSTENIBLE\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/\",\"name\":\"Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD) - in\u00e8dit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/residus_construccio.jpg\",\"datePublished\":\"2025-03-24T21:44:01+00:00\",\"dateModified\":\"2025-03-24T22:01:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\"},\"description\":\"El sector de la construcci\u00f3n es el que m\u00e1s residuos genera: el 40% de los residuos en Europa y el 29,8% en Espa\u00f1a. En Catalu\u00f1a, en 2023 se generaron m\u00e1s de siete millones de toneladas de residuos. Estos incluyen materiales como hormig\u00f3n, ladrillos, yeso, madera, vidrio, metales, pl\u00e1stico, disolventes, amianto y tierras excavadas, y la mayor\u00eda acaban en vertederos o son incinerados. Por ello, es necesario encontrar soluciones innovadoras para minimizar y fomentar la reutilizaci\u00f3n y el reciclaje de los residuos de construcci\u00f3n y demolici\u00f3n (RCD). La soluci\u00f3n pasa por impulsar modelos de negocio circulares dentro del sector, y c\u00f3mo hacerlo es el reto al que dar\u00e1 respuesta el proyecto \u00abAn\u00e1lisis de nuevos modelos de negocio circulares en torno a los RCD y validaci\u00f3n a trav\u00e9s de una fase de experimentaci\u00f3n en obra\u00bb, impulsado por el Cl\u00faster de Residuos de Catalu\u00f1a (CREC), y con la participaci\u00f3n de in\u00e8dit.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/residus_construccio.jpg\",\"contentUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/residus_construccio.jpg\",\"width\":1200,\"height\":672,\"caption\":\"residus construccio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/\",\"name\":\"in\u00e8dit\",\"description\":\"Dise\u00f1amos soluciones circulares y sostenibles para un futuro mejor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\",\"name\":\"Codina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"caption\":\"Codina\"},\"url\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/author\\\/inedit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD) - in\u00e8dit","description":"El sector de la construcci\u00f3n es el que m\u00e1s residuos genera: el 40% de los residuos en Europa y el 29,8% en Espa\u00f1a. En Catalu\u00f1a, en 2023 se generaron m\u00e1s de siete millones de toneladas de residuos. Estos incluyen materiales como hormig\u00f3n, ladrillos, yeso, madera, vidrio, metales, pl\u00e1stico, disolventes, amianto y tierras excavadas, y la mayor\u00eda acaban en vertederos o son incinerados. Por ello, es necesario encontrar soluciones innovadoras para minimizar y fomentar la reutilizaci\u00f3n y el reciclaje de los residuos de construcci\u00f3n y demolici\u00f3n (RCD). La soluci\u00f3n pasa por impulsar modelos de negocio circulares dentro del sector, y c\u00f3mo hacerlo es el reto al que dar\u00e1 respuesta el proyecto \u00abAn\u00e1lisis de nuevos modelos de negocio circulares en torno a los RCD y validaci\u00f3n a trav\u00e9s de una fase de experimentaci\u00f3n en obra\u00bb, impulsado por el Cl\u00faster de Residuos de Catalu\u00f1a (CREC), y con la participaci\u00f3n de in\u00e8dit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/","og_locale":"es_ES","og_type":"article","og_title":"Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD) - in\u00e8dit","og_description":"El sector de la construcci\u00f3n es el que m\u00e1s residuos genera: el 40% de los residuos en Europa y el 29,8% en Espa\u00f1a. En Catalu\u00f1a, en 2023 se generaron m\u00e1s de siete millones de toneladas de residuos. Estos incluyen materiales como hormig\u00f3n, ladrillos, yeso, madera, vidrio, metales, pl\u00e1stico, disolventes, amianto y tierras excavadas, y la mayor\u00eda acaban en vertederos o son incinerados. Por ello, es necesario encontrar soluciones innovadoras para minimizar y fomentar la reutilizaci\u00f3n y el reciclaje de los residuos de construcci\u00f3n y demolici\u00f3n (RCD). La soluci\u00f3n pasa por impulsar modelos de negocio circulares dentro del sector, y c\u00f3mo hacerlo es el reto al que dar\u00e1 respuesta el proyecto \u00abAn\u00e1lisis de nuevos modelos de negocio circulares en torno a los RCD y validaci\u00f3n a trav\u00e9s de una fase de experimentaci\u00f3n en obra\u00bb, impulsado por el Cl\u00faster de Residuos de Catalu\u00f1a (CREC), y con la participaci\u00f3n de in\u00e8dit.","og_url":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/","og_site_name":"in\u00e8dit","article_publisher":"https:\/\/www.facebook.com\/ineditinnovacio\/?ref=page_internal","article_published_time":"2025-03-24T21:44:01+00:00","article_modified_time":"2025-03-24T22:01:42+00:00","og_image":[{"width":1200,"height":672,"url":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/residus_construccio.jpg","type":"image\/jpeg"}],"author":"Codina","twitter_card":"summary_large_image","twitter_creator":"@ineditinnova","twitter_site":"@ineditinnova","twitter_misc":{"Escrito por":"Codina","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/#article","isPartOf":{"@id":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/"},"author":{"name":"Codina","@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5"},"headline":"Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD)","datePublished":"2025-03-24T21:44:01+00:00","dateModified":"2025-03-24T22:01:42+00:00","mainEntityOfPage":{"@id":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/"},"wordCount":859,"image":{"@id":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/#primaryimage"},"thumbnailUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/residus_construccio.jpg","keywords":["NOTICIA"],"articleSection":["ESTRATEGIA DE NEGOCIO SOSTENIBLE"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/","url":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/","name":"Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD) - in\u00e8dit","isPartOf":{"@id":"https:\/\/ineditinnova.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/#primaryimage"},"image":{"@id":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/#primaryimage"},"thumbnailUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/residus_construccio.jpg","datePublished":"2025-03-24T21:44:01+00:00","dateModified":"2025-03-24T22:01:42+00:00","author":{"@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5"},"description":"El sector de la construcci\u00f3n es el que m\u00e1s residuos genera: el 40% de los residuos en Europa y el 29,8% en Espa\u00f1a. En Catalu\u00f1a, en 2023 se generaron m\u00e1s de siete millones de toneladas de residuos. Estos incluyen materiales como hormig\u00f3n, ladrillos, yeso, madera, vidrio, metales, pl\u00e1stico, disolventes, amianto y tierras excavadas, y la mayor\u00eda acaban en vertederos o son incinerados. Por ello, es necesario encontrar soluciones innovadoras para minimizar y fomentar la reutilizaci\u00f3n y el reciclaje de los residuos de construcci\u00f3n y demolici\u00f3n (RCD). La soluci\u00f3n pasa por impulsar modelos de negocio circulares dentro del sector, y c\u00f3mo hacerlo es el reto al que dar\u00e1 respuesta el proyecto \u00abAn\u00e1lisis de nuevos modelos de negocio circulares en torno a los RCD y validaci\u00f3n a trav\u00e9s de una fase de experimentaci\u00f3n en obra\u00bb, impulsado por el Cl\u00faster de Residuos de Catalu\u00f1a (CREC), y con la participaci\u00f3n de in\u00e8dit.","breadcrumb":{"@id":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/#primaryimage","url":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/residus_construccio.jpg","contentUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/03\/residus_construccio.jpg","width":1200,"height":672,"caption":"residus construccio"},{"@type":"BreadcrumbList","@id":"https:\/\/ineditinnova.com\/es\/models-de-negoci-circulars-per-prevenir-minimitzar-i-valoritzar-els-residus-de-la-construccio-i-la-demolicio-rcd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/ineditinnova.com\/es\/"},{"@type":"ListItem","position":2,"name":"Modelos de negocio circulares para prevenir, minimizar y valorizar los residuos de construcci\u00f3n y demolici\u00f3n (RCD)"}]},{"@type":"WebSite","@id":"https:\/\/ineditinnova.com\/en\/#website","url":"https:\/\/ineditinnova.com\/en\/","name":"in\u00e8dit","description":"Dise\u00f1amos soluciones circulares y sostenibles para un futuro mejor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ineditinnova.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5","name":"Codina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","caption":"Codina"},"url":"https:\/\/ineditinnova.com\/es\/author\/inedit\/"}]}},"_links":{"self":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/11197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/comments?post=11197"}],"version-history":[{"count":1,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/11197\/revisions"}],"predecessor-version":[{"id":11199,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/11197\/revisions\/11199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/media\/11191"}],"wp:attachment":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/media?parent=11197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/categories?post=11197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/tags?post=11197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}