{"id":11328,"date":"2025-04-28T21:22:20","date_gmt":"2025-04-28T21:22:20","guid":{"rendered":"https:\/\/ineditinnova.com\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/"},"modified":"2025-04-28T21:29:00","modified_gmt":"2025-04-28T21:29:00","slug":"la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic","status":"publish","type":"post","link":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/","title":{"rendered":"La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">La Comisi\u00f3n Europea adopt\u00f3, el 16 de abril, el plan de trabajo 2025-2030 del Reglamento de Ecodise\u00f1o para Productos Sostenibles (ESPR) y del Reglamento marco de Etiquetado Energ\u00e9tico (ELFR). El plan proporciona la lista de los productos que deber\u00e1n priorizarse a la hora de introducir los requisitos de ecodise\u00f1o y etiquetado energ\u00e9tico en los pr\u00f3ximos cinco a\u00f1os, y <strong>su objetivo es impulsar productos m\u00e1s sostenibles, reparables, circulares y energ\u00e9ticamente m\u00e1s eficientes en toda Europa<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">El plan de trabajo establece el a\u00f1o l\u00edmite para que se adopten los actos delegados que regular\u00e1n cada uno de los productos priorizados, que son: hierro y acero (2026), aluminio (2027), ropa (2027), neum\u00e1ticos (2027), muebles (2028) y colchones (2029).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">Este nuevo plan de trabajo actual <strong>da continuidad a la tarea iniciada con diecis\u00e9is productos relacionados con la energ\u00eda<\/strong> \u2014lavavajillas, motores el\u00e9ctricos, cargadores de veh\u00edculos el\u00e9ctricos o pantallas, entre otros\u2014 <strong>del plan de trabajo 2022-2024 de ecodise\u00f1o y etiquetado energ\u00e9tico.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">El nuevo plan de trabajo pone el foco en los materiales por una raz\u00f3n muy sencilla: \u00abEn los \u00faltimos a\u00f1os se ha trabajado mucho para mejorar la eficiencia energ\u00e9tica, y al mejorar la eficiencia energ\u00e9tica ha salido m\u00e1s a la luz el impacto de los materiales\u00bb, se\u00f1ala <strong>Carles Gasol<\/strong>, director de Desarrollo de negocio de in\u00e8dit. Aun as\u00ed, <strong>\u00abla durabilidad de los productos deber\u00e1 ir de la mano de la eficiencia energ\u00e9tica\u00bb<\/strong>, apunta, porque \u00abno tendr\u00eda sentido que un producto durara mucho y fuera muy reparable si, a medida que pasan los a\u00f1os, incrementa su consumo energ\u00e9tico\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Requisitos de ecodise\u00f1o, etiquetaje energ\u00e9tico, reparabilidad y reciclabilidad<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">Los futuros requisitos de ecodise\u00f1o y etiquetado energ\u00e9tico considerar\u00e1n, por un lado, el rendimiento del producto \u2014la durabilidad m\u00ednima, la eficiencia m\u00ednima en recursos y energ\u00eda, la disponibilidad de piezas de repuesto o el contenido m\u00ednimo de material reciclado\u2014 y\/o la informaci\u00f3n sobre el producto en s\u00ed, incluyendo caracter\u00edsticas clave como la huella de carbono y ambiental de los productos. Esta informaci\u00f3n estar\u00e1 disponible principalmente a trav\u00e9s del Pasaporte Digital de Producto o, en el caso de los productos con etiqueta energ\u00e9tica, a trav\u00e9s del Registro Europeo de Productos para el Etiquetado Energ\u00e9tico (EPREL).<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La Comisi\u00f3n Europea introduicir\u00e1, en 2027, requisitos en materia de reparabilidad en productos como la electr\u00f3nica de consumo y los peque\u00f1os electrodom\u00e9sticos<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">Por otro lado, en 2027 la CE introducir\u00e1 requisitos en materia de reparabilidad en productos como la electr\u00f3nica de consumo y los peque\u00f1os electrodom\u00e9sticos. Se introducir\u00e1 un \u00edndice de reparabilidad para los productos con mayor potencial de ser reparados, y en 2029 se introducir\u00e1n requisitos sobre la reciclabilidad de los equipos el\u00e9ctricos y electr\u00f3nicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">Con estas medidas, <strong>se quiere facilitar la elecci\u00f3n de productos m\u00e1s sostenibles y energ\u00e9ticamente eficientes por parte de los consumidores.<\/strong> A esto hay que a\u00f1adir que, seg\u00fan la Comisi\u00f3n Europea, \u00abla armonizaci\u00f3n de los requisitos en materia de sostenibilidad de los productos en Europa fortalecer\u00e1 el mercado \u00fanico, evitar\u00e1 barreras comerciales, mejorar\u00e1 la igualdad de condiciones, reducir\u00e1 la carga administrativa y reforzar\u00e1 la competitividad global de las empresas que ofrecen productos sostenibles\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\"><strong>En in\u00e8dit, contamos con diecis\u00e9is a\u00f1os de experiencia en el \u00e1mbito del ecodise\u00f1o de productos y servicios. <\/strong>Proponemos soluciones para optimizar los materiales, alargar la vida \u00fatil de los productos, incrementar su reciclabilidad, optimizar los procesos, crear productos modulares y transformar los modelos de negocio, para mejorar la propuesta de valor y la posici\u00f3n en el mercado del cliente.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-fe48e5de wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75\"><a class=\"wp-block-button__link has-custom-font-size wp-element-button\" href=\"https:\/\/ineditinnova.com\/es\/contacto\/\" style=\"font-size:25px\"><strong>Contacta con nosotros<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Europea adopt\u00f3, el 16 de abril, el plan de trabajo 2025-2030 del Reglamento de Ecodise\u00f1o para Productos Sostenibles (ESPR) y del Reglamento marco de Etiquetado Energ\u00e9tico (ELFR). El plan proporciona la lista de los productos que deber\u00e1n priorizarse a la hora de introducir los requisitos de ecodise\u00f1o y etiquetado energ\u00e9tico en los pr\u00f3ximos&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/\" title=\"Read La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":11324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21],"tags":[54],"class_list":["post-11328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecodiseno","tag-noticia-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico - in\u00e8dit<\/title>\n<meta name=\"description\" content=\"La Comisi\u00f3n Europea adopt\u00f3, el 16 de abril, el plan de trabajo 2025-2030 del Reglamento de Ecodise\u00f1o para Productos Sostenibles (ESPR) y del Reglamento marco de Etiquetado Energ\u00e9tico (ELFR). El plan proporciona la lista de los productos que deber\u00e1n priorizarse a la hora de introducir los requisitos de ecodise\u00f1o y etiquetado energ\u00e9tico en los pr\u00f3ximos cinco a\u00f1os, y su objetivo es impulsar productos m\u00e1s sostenibles, reparables, circulares y energ\u00e9ticamente m\u00e1s eficientes en toda Europa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico - in\u00e8dit\" \/>\n<meta property=\"og:description\" content=\"La Comisi\u00f3n Europea adopt\u00f3, el 16 de abril, el plan de trabajo 2025-2030 del Reglamento de Ecodise\u00f1o para Productos Sostenibles (ESPR) y del Reglamento marco de Etiquetado Energ\u00e9tico (ELFR). El plan proporciona la lista de los productos que deber\u00e1n priorizarse a la hora de introducir los requisitos de ecodise\u00f1o y etiquetado energ\u00e9tico en los pr\u00f3ximos cinco a\u00f1os, y su objetivo es impulsar productos m\u00e1s sostenibles, reparables, circulares y energ\u00e9ticamente m\u00e1s eficientes en toda Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/\" \/>\n<meta property=\"og:site_name\" content=\"in\u00e8dit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ineditinnovacio\/?ref=page_internal\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T21:22:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T21:29:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/04\/European_Commission_in_Brussels_petita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Codina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ineditinnova\" \/>\n<meta name=\"twitter:site\" content=\"@ineditinnova\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Codina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/\"},\"author\":{\"name\":\"Codina\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\"},\"headline\":\"La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico\",\"datePublished\":\"2025-04-28T21:22:20+00:00\",\"dateModified\":\"2025-04-28T21:29:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/\"},\"wordCount\":642,\"image\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/European_Commission_in_Brussels_petita.jpg\",\"keywords\":[\"NOTICIA\"],\"articleSection\":[\"Ecodise\u00f1o de productos y servicios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/\",\"name\":\"La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico - in\u00e8dit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/European_Commission_in_Brussels_petita.jpg\",\"datePublished\":\"2025-04-28T21:22:20+00:00\",\"dateModified\":\"2025-04-28T21:29:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\"},\"description\":\"La Comisi\u00f3n Europea adopt\u00f3, el 16 de abril, el plan de trabajo 2025-2030 del Reglamento de Ecodise\u00f1o para Productos Sostenibles (ESPR) y del Reglamento marco de Etiquetado Energ\u00e9tico (ELFR). El plan proporciona la lista de los productos que deber\u00e1n priorizarse a la hora de introducir los requisitos de ecodise\u00f1o y etiquetado energ\u00e9tico en los pr\u00f3ximos cinco a\u00f1os, y su objetivo es impulsar productos m\u00e1s sostenibles, reparables, circulares y energ\u00e9ticamente m\u00e1s eficientes en toda Europa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/European_Commission_in_Brussels_petita.jpg\",\"contentUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/European_Commission_in_Brussels_petita.jpg\",\"width\":1200,\"height\":801,\"caption\":\"Comissi\u00f3 Europea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/\",\"name\":\"in\u00e8dit\",\"description\":\"Dise\u00f1amos soluciones circulares y sostenibles para un futuro mejor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\",\"name\":\"Codina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"caption\":\"Codina\"},\"url\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/author\\\/inedit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico - in\u00e8dit","description":"La Comisi\u00f3n Europea adopt\u00f3, el 16 de abril, el plan de trabajo 2025-2030 del Reglamento de Ecodise\u00f1o para Productos Sostenibles (ESPR) y del Reglamento marco de Etiquetado Energ\u00e9tico (ELFR). El plan proporciona la lista de los productos que deber\u00e1n priorizarse a la hora de introducir los requisitos de ecodise\u00f1o y etiquetado energ\u00e9tico en los pr\u00f3ximos cinco a\u00f1os, y su objetivo es impulsar productos m\u00e1s sostenibles, reparables, circulares y energ\u00e9ticamente m\u00e1s eficientes en toda Europa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/","og_locale":"es_ES","og_type":"article","og_title":"La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico - in\u00e8dit","og_description":"La Comisi\u00f3n Europea adopt\u00f3, el 16 de abril, el plan de trabajo 2025-2030 del Reglamento de Ecodise\u00f1o para Productos Sostenibles (ESPR) y del Reglamento marco de Etiquetado Energ\u00e9tico (ELFR). El plan proporciona la lista de los productos que deber\u00e1n priorizarse a la hora de introducir los requisitos de ecodise\u00f1o y etiquetado energ\u00e9tico en los pr\u00f3ximos cinco a\u00f1os, y su objetivo es impulsar productos m\u00e1s sostenibles, reparables, circulares y energ\u00e9ticamente m\u00e1s eficientes en toda Europa.","og_url":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/","og_site_name":"in\u00e8dit","article_publisher":"https:\/\/www.facebook.com\/ineditinnovacio\/?ref=page_internal","article_published_time":"2025-04-28T21:22:20+00:00","article_modified_time":"2025-04-28T21:29:00+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/04\/European_Commission_in_Brussels_petita.jpg","type":"image\/jpeg"}],"author":"Codina","twitter_card":"summary_large_image","twitter_creator":"@ineditinnova","twitter_site":"@ineditinnova","twitter_misc":{"Escrito por":"Codina","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/#article","isPartOf":{"@id":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/"},"author":{"name":"Codina","@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5"},"headline":"La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico","datePublished":"2025-04-28T21:22:20+00:00","dateModified":"2025-04-28T21:29:00+00:00","mainEntityOfPage":{"@id":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/"},"wordCount":642,"image":{"@id":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/#primaryimage"},"thumbnailUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/04\/European_Commission_in_Brussels_petita.jpg","keywords":["NOTICIA"],"articleSection":["Ecodise\u00f1o de productos y servicios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/","url":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/","name":"La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico - in\u00e8dit","isPartOf":{"@id":"https:\/\/ineditinnova.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/#primaryimage"},"image":{"@id":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/#primaryimage"},"thumbnailUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/04\/European_Commission_in_Brussels_petita.jpg","datePublished":"2025-04-28T21:22:20+00:00","dateModified":"2025-04-28T21:29:00+00:00","author":{"@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5"},"description":"La Comisi\u00f3n Europea adopt\u00f3, el 16 de abril, el plan de trabajo 2025-2030 del Reglamento de Ecodise\u00f1o para Productos Sostenibles (ESPR) y del Reglamento marco de Etiquetado Energ\u00e9tico (ELFR). El plan proporciona la lista de los productos que deber\u00e1n priorizarse a la hora de introducir los requisitos de ecodise\u00f1o y etiquetado energ\u00e9tico en los pr\u00f3ximos cinco a\u00f1os, y su objetivo es impulsar productos m\u00e1s sostenibles, reparables, circulares y energ\u00e9ticamente m\u00e1s eficientes en toda Europa.","breadcrumb":{"@id":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/#primaryimage","url":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/04\/European_Commission_in_Brussels_petita.jpg","contentUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2025\/04\/European_Commission_in_Brussels_petita.jpg","width":1200,"height":801,"caption":"Comissi\u00f3 Europea"},{"@type":"BreadcrumbList","@id":"https:\/\/ineditinnova.com\/es\/la-ce-adopta-el-nou-pla-de-treball-en-materia-decodisseny-i-etiquetatge-energetic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/ineditinnova.com\/es\/"},{"@type":"ListItem","position":2,"name":"La CE adopta el nuevo plan de trabajo en materia de ecodise\u00f1o y etiquetado energ\u00e9tico"}]},{"@type":"WebSite","@id":"https:\/\/ineditinnova.com\/en\/#website","url":"https:\/\/ineditinnova.com\/en\/","name":"in\u00e8dit","description":"Dise\u00f1amos soluciones circulares y sostenibles para un futuro mejor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ineditinnova.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5","name":"Codina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","caption":"Codina"},"url":"https:\/\/ineditinnova.com\/es\/author\/inedit\/"}]}},"_links":{"self":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/11328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/comments?post=11328"}],"version-history":[{"count":2,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/11328\/revisions"}],"predecessor-version":[{"id":11332,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/11328\/revisions\/11332"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/media\/11324"}],"wp:attachment":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/media?parent=11328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/categories?post=11328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/tags?post=11328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}