{"id":13879,"date":"2026-04-17T15:49:47","date_gmt":"2026-04-17T15:49:47","guid":{"rendered":"https:\/\/ineditinnova.com\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/"},"modified":"2026-04-17T16:54:23","modified_gmt":"2026-04-17T16:54:23","slug":"un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal","status":"publish","type":"post","link":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/","title":{"rendered":"Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Cada a\u00f1o, en el mundo se pierden materiales por un valor de <strong>25,4 billones de euros<\/strong> como consecuencia de la econom\u00eda lineal, basada en el modelo de extraer, producir, usar y desechar. Esta p\u00e9rdida se explica por un uso ineficiente de los recursos, como, por ejemplo, productos que se descartan antes de tiempo y activos que no se aprovechan lo suficiente. Teniendo en cuenta que el Producto Interior Bruto (PIB) global es de 82,6 billones de euros, esto equivale a decir que, <strong>por cada 3 euros de valor econ\u00f3mico que se crea, se pierde 1. <\/strong>Es la primera vez que el <em><em><em><em><a href=\"https:\/\/dashboard.circularity-gap.world\/report\/2026\/cgr-2026-overview\">Circularity Gap Report 2026<\/a><\/em><\/em><\/em><\/em>, elaborado por <a href=\"https:\/\/www.circle-economy.com\/\">Circle Economy<\/a> y <a href=\"https:\/\/www.deloitte.com\/\">Deloitte<\/a>, cuantifica esta brecha de valor \u2014o <em>Value Gap<\/em>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Una p\u00e9rdida invisible para los indicadores econ\u00f3micos<\/strong><\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"377\" data-src=\"https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/hd_CGR_2026_Visuals3_22ce07aeeb-1024x377.jpg\" alt=\"\" class=\"wp-image-13873 lazyload\" data-srcset=\"https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/hd_CGR_2026_Visuals3_22ce07aeeb-1024x377.jpg 1024w, https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/hd_CGR_2026_Visuals3_22ce07aeeb-300x110.jpg 300w, https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/hd_CGR_2026_Visuals3_22ce07aeeb-768x283.jpg 768w, https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/hd_CGR_2026_Visuals3_22ce07aeeb.jpg 1280w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/377;\" \/><figcaption class=\"wp-element-caption\">Fuente: <em>Circularity Gap Report 2026<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las m\u00e9tricas econ\u00f3micas convencionales no tienen en cuenta la p\u00e9rdida de valor que provoca la linealidad. Indicadores como el PIB miden la actividad econ\u00f3mica, pero no la retenci\u00f3n de valor ni su erosi\u00f3n, como el agotamiento de los recursos o la generaci\u00f3n de residuos. Esto hace que esta p\u00e9rdida estructural permanezca invisible en la toma de decisiones econ\u00f3micas. En este contexto, la brecha de valor se define en t\u00e9rminos econ\u00f3micos y se expresa en precios, con el PIB como aproximaci\u00f3n del valor total generado. Seg\u00fan el informe, <strong>incorporar esta brecha junto con el PIB \u00abpermite obtener una medida m\u00e1s realista de la creaci\u00f3n neta de valor<\/strong>, poner de manifiesto el valor econ\u00f3mico que se pierde estructuralmente debido a la linealidad y evidenciar el alcance de la oportunidad que representan las estrategias circulares\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>La brecha de valor pone en relieve el valor econ\u00f3mico que se pierde a trav\u00e9s del modelo lineal y demuestra las oportunidades que representan las estrategias de circularidad<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La cifra representa el valor econ\u00f3mico evitable que se pierde debido a las pr\u00e1cticas lineales y que podr\u00eda recuperarse con un modelo de econom\u00eda circular, orientado a la retenci\u00f3n y recuperaci\u00f3n del valor a largo plazo. M\u00e1s all\u00e1 de los costes econ\u00f3micos directos, <strong>estas p\u00e9rdidas reflejan impactos ambientales y sociales a menudo ocultos<\/strong>, como la contaminaci\u00f3n, el agotamiento de los recursos, los efectos sobre la salud humana o la reducci\u00f3n de la productividad laboral. Para los autores del estudio, la brecha de valor \u00abno es solo una medida de p\u00e9rdida, sino una oportunidad para impulsar intervenciones circulares que permitan retener m\u00e1s valor, reducir la generaci\u00f3n de residuos y reforzar la prosperidad a largo plazo\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong>Una p\u00e9rdida estructural que requiere cambios sist\u00e9micos<\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El informe se\u00f1ala que la p\u00e9rdida de valor es estructural y sist\u00e9mica, es decir, deriva del propio dise\u00f1o de la econom\u00eda lineal y no de ineficiencias puntuales. <\/p>\n\n\n\n<figure class=\"wp-block-pullquote\"><blockquote><p>Para hacer frente a esta p\u00e9rdida de valor, es necesario un redise\u00f1o sist\u00e9mico de manera en que se obtienen los materiales, se utilizan, se retienen y circulan a trav\u00e9s de la econom\u00eda<\/p><\/blockquote><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para hacerle frente, por tanto, \u00abes necesario un redise\u00f1o sist\u00e9mico de la manera en que se obtienen los materiales, se utilizan, se retienen y circulan a trav\u00e9s de la econom\u00eda\u00bb. Esto implica transformar los sistemas de producci\u00f3n y consumo y aplicar cambios estructurales en \u00e1mbitos clave como la vivienda, la alimentaci\u00f3n, la movilidad o la manufactura. Este proceso requiere, adem\u00e1s, una acci\u00f3n coordinada a lo largo de toda la cadena de valor, ya que ning\u00fan actor puede abordar por s\u00ed solo una problem\u00e1tica de esta magnitud.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong><strong>M\u00e1s all\u00e1 del reciclaje: el potencial de la circularidad<\/strong><\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La circularidad consiste, fundamentalmente, en reducir el uso de recursos y maximizar su valor a lo largo del tiempo, y no solo en reciclar materiales. En este sentido,<strong> existe un gran potencial en materiales que son reciclables pero que actualmente no se recuperan<\/strong>, como los productos de consumo de vida corta, los veh\u00edculos o los materiales de construcci\u00f3n. Seg\u00fan el informe, si se reciclaran todos estos flujos, el \u00edndice de circularidad podr\u00eda crecer un 25%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, una parte importante de los materiales v\u00edrgenes y no renovables son dif\u00edciles de reciclar o tienen poco valor. Por ello, es clave priorizar estrategias que minimicen los residuos y fomenten la reutilizaci\u00f3n, especialmente en los materiales de mayor valor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El <em>Circularity Gap Report 2026<\/em> muestra que <strong>la gran mayor\u00eda de los materiales que entran en la econom\u00eda siguen siendo v\u00edrgenes<\/strong>, y que a pesar de que el consumo de materiales reciclados aumenta, el de materiales v\u00edrgenes lo hace a un ritmo superior. En los \u00faltimos cincuenta a\u00f1os, la extracci\u00f3n de materiales v\u00edrgenes se ha m\u00e1s que triplicado y, si no se producen cambios estructurales, podr\u00eda aumentar un 60% adicional hasta 2060.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada a\u00f1o, en el mundo se pierden materiales por un valor de 25,4 billones de euros como consecuencia de la econom\u00eda lineal, basada en el modelo de extraer, producir, usar y desechar. Esta p\u00e9rdida se explica por un uso ineficiente de los recursos, como, por ejemplo, productos que se descartan antes de tiempo y activos&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/\" title=\"Read Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":13872,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43,31,21,49],"tags":[56,54],"class_list":["post-13879","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-metricas","category-cadena","category-ecodiseno","category-territorio","tag-informe-es","tag-noticia-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal - in\u00e8dit<\/title>\n<meta name=\"description\" content=\"Cada a\u00f1o, en el mundo se pierden materiales por un valor de 25,4 billones de euros como consecuencia de la econom\u00eda lineal, basada en el modelo de extraer, producir, usar y desechar. Esta p\u00e9rdida se explica por un uso ineficiente de los recursos: productos que se descartan antes de tiempo y activos que no se aprovechan lo suficiente. Teniendo en cuenta que el Producto Interior Bruto (PIB) global es de 82,6 billones de euros, esto equivale a decir que, por cada 3 euros de valor econ\u00f3mico que se crea, se pierde 1. Es la primera vez que el Circularity Gap Report 2025, elaborado por Circle Economy y Deloitte, cuantifica esta brecha de valor \u2014o Value Gap.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal - in\u00e8dit\" \/>\n<meta property=\"og:description\" content=\"Cada a\u00f1o, en el mundo se pierden materiales por un valor de 25,4 billones de euros como consecuencia de la econom\u00eda lineal, basada en el modelo de extraer, producir, usar y desechar. Esta p\u00e9rdida se explica por un uso ineficiente de los recursos: productos que se descartan antes de tiempo y activos que no se aprovechan lo suficiente. Teniendo en cuenta que el Producto Interior Bruto (PIB) global es de 82,6 billones de euros, esto equivale a decir que, por cada 3 euros de valor econ\u00f3mico que se crea, se pierde 1. Es la primera vez que el Circularity Gap Report 2025, elaborado por Circle Economy y Deloitte, cuantifica esta brecha de valor \u2014o Value Gap.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/\" \/>\n<meta property=\"og:site_name\" content=\"in\u00e8dit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ineditinnovacio\/?ref=page_internal\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-17T15:49:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T16:54:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/circularity_gap_report.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1357\" \/>\n\t<meta property=\"og:image:height\" content=\"1018\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Codina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ineditinnova\" \/>\n<meta name=\"twitter:site\" content=\"@ineditinnova\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Codina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/\"},\"author\":{\"name\":\"Codina\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\"},\"headline\":\"Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal\",\"datePublished\":\"2026-04-17T15:49:47+00:00\",\"dateModified\":\"2026-04-17T16:54:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/\"},\"wordCount\":836,\"image\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/circularity_gap_report.jpg\",\"keywords\":[\"INFORME\",\"NOTICIA\"],\"articleSection\":[\"CUANTIFICACI\u00d3N DE IMPACTOS AMBIENTALES\",\"ESTRATEGIA DE NEGOCIO SOSTENIBLE\",\"Ecodise\u00f1o de productos y servicios\",\"TERRITORIO CIRCULAR\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/\",\"name\":\"Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal - in\u00e8dit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/circularity_gap_report.jpg\",\"datePublished\":\"2026-04-17T15:49:47+00:00\",\"dateModified\":\"2026-04-17T16:54:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\"},\"description\":\"Cada a\u00f1o, en el mundo se pierden materiales por un valor de 25,4 billones de euros como consecuencia de la econom\u00eda lineal, basada en el modelo de extraer, producir, usar y desechar. Esta p\u00e9rdida se explica por un uso ineficiente de los recursos: productos que se descartan antes de tiempo y activos que no se aprovechan lo suficiente. Teniendo en cuenta que el Producto Interior Bruto (PIB) global es de 82,6 billones de euros, esto equivale a decir que, por cada 3 euros de valor econ\u00f3mico que se crea, se pierde 1. Es la primera vez que el Circularity Gap Report 2025, elaborado por Circle Economy y Deloitte, cuantifica esta brecha de valor \u2014o Value Gap.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/circularity_gap_report.jpg\",\"contentUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/circularity_gap_report.jpg\",\"width\":1357,\"height\":1018,\"caption\":\"CGR 26\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/\",\"name\":\"in\u00e8dit\",\"description\":\"Dise\u00f1amos soluciones circulares y sostenibles para un futuro mejor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\",\"name\":\"Codina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"caption\":\"Codina\"},\"url\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/author\\\/inedit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal - in\u00e8dit","description":"Cada a\u00f1o, en el mundo se pierden materiales por un valor de 25,4 billones de euros como consecuencia de la econom\u00eda lineal, basada en el modelo de extraer, producir, usar y desechar. Esta p\u00e9rdida se explica por un uso ineficiente de los recursos: productos que se descartan antes de tiempo y activos que no se aprovechan lo suficiente. Teniendo en cuenta que el Producto Interior Bruto (PIB) global es de 82,6 billones de euros, esto equivale a decir que, por cada 3 euros de valor econ\u00f3mico que se crea, se pierde 1. Es la primera vez que el Circularity Gap Report 2025, elaborado por Circle Economy y Deloitte, cuantifica esta brecha de valor \u2014o Value Gap.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/","og_locale":"es_ES","og_type":"article","og_title":"Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal - in\u00e8dit","og_description":"Cada a\u00f1o, en el mundo se pierden materiales por un valor de 25,4 billones de euros como consecuencia de la econom\u00eda lineal, basada en el modelo de extraer, producir, usar y desechar. Esta p\u00e9rdida se explica por un uso ineficiente de los recursos: productos que se descartan antes de tiempo y activos que no se aprovechan lo suficiente. Teniendo en cuenta que el Producto Interior Bruto (PIB) global es de 82,6 billones de euros, esto equivale a decir que, por cada 3 euros de valor econ\u00f3mico que se crea, se pierde 1. Es la primera vez que el Circularity Gap Report 2025, elaborado por Circle Economy y Deloitte, cuantifica esta brecha de valor \u2014o Value Gap.","og_url":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/","og_site_name":"in\u00e8dit","article_publisher":"https:\/\/www.facebook.com\/ineditinnovacio\/?ref=page_internal","article_published_time":"2026-04-17T15:49:47+00:00","article_modified_time":"2026-04-17T16:54:23+00:00","og_image":[{"width":1357,"height":1018,"url":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/circularity_gap_report.jpg","type":"image\/jpeg"}],"author":"Codina","twitter_card":"summary_large_image","twitter_creator":"@ineditinnova","twitter_site":"@ineditinnova","twitter_misc":{"Escrito por":"Codina","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/#article","isPartOf":{"@id":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/"},"author":{"name":"Codina","@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5"},"headline":"Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal","datePublished":"2026-04-17T15:49:47+00:00","dateModified":"2026-04-17T16:54:23+00:00","mainEntityOfPage":{"@id":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/"},"wordCount":836,"image":{"@id":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/#primaryimage"},"thumbnailUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/circularity_gap_report.jpg","keywords":["INFORME","NOTICIA"],"articleSection":["CUANTIFICACI\u00d3N DE IMPACTOS AMBIENTALES","ESTRATEGIA DE NEGOCIO SOSTENIBLE","Ecodise\u00f1o de productos y servicios","TERRITORIO CIRCULAR"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/","url":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/","name":"Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal - in\u00e8dit","isPartOf":{"@id":"https:\/\/ineditinnova.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/#primaryimage"},"image":{"@id":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/#primaryimage"},"thumbnailUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/circularity_gap_report.jpg","datePublished":"2026-04-17T15:49:47+00:00","dateModified":"2026-04-17T16:54:23+00:00","author":{"@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5"},"description":"Cada a\u00f1o, en el mundo se pierden materiales por un valor de 25,4 billones de euros como consecuencia de la econom\u00eda lineal, basada en el modelo de extraer, producir, usar y desechar. Esta p\u00e9rdida se explica por un uso ineficiente de los recursos: productos que se descartan antes de tiempo y activos que no se aprovechan lo suficiente. Teniendo en cuenta que el Producto Interior Bruto (PIB) global es de 82,6 billones de euros, esto equivale a decir que, por cada 3 euros de valor econ\u00f3mico que se crea, se pierde 1. Es la primera vez que el Circularity Gap Report 2025, elaborado por Circle Economy y Deloitte, cuantifica esta brecha de valor \u2014o Value Gap.","breadcrumb":{"@id":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/#primaryimage","url":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/circularity_gap_report.jpg","contentUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2026\/04\/circularity_gap_report.jpg","width":1357,"height":1018,"caption":"CGR 26"},{"@type":"BreadcrumbList","@id":"https:\/\/ineditinnova.com\/es\/un-terc-del-valor-economic-global-es-perd-per-la-ineficiencia-del-model-lineal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/ineditinnova.com\/es\/"},{"@type":"ListItem","position":2,"name":"Un tercio del valor econ\u00f3mico global se pierde por la ineficiencia del modelo lineal"}]},{"@type":"WebSite","@id":"https:\/\/ineditinnova.com\/en\/#website","url":"https:\/\/ineditinnova.com\/en\/","name":"in\u00e8dit","description":"Dise\u00f1amos soluciones circulares y sostenibles para un futuro mejor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ineditinnova.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5","name":"Codina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","caption":"Codina"},"url":"https:\/\/ineditinnova.com\/es\/author\/inedit\/"}]}},"_links":{"self":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/13879","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/comments?post=13879"}],"version-history":[{"count":9,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/13879\/revisions"}],"predecessor-version":[{"id":13904,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/13879\/revisions\/13904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/media\/13872"}],"wp:attachment":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/media?parent=13879"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/categories?post=13879"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/tags?post=13879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}