{"id":7207,"date":"2023-11-28T16:10:20","date_gmt":"2023-11-28T16:10:20","guid":{"rendered":"https:\/\/ineditinnova.com\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/"},"modified":"2023-11-28T16:19:55","modified_gmt":"2023-11-28T16:19:55","slug":"els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit","status":"publish","type":"post","link":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/","title":{"rendered":"Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit"},"content":{"rendered":"\n\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">Las 202 bodegas catalanas adscritas a la Denominaci\u00f3n de Origen (DO) Catalunya contar\u00e1n pr\u00f3ximamente con una herramienta en l\u00ednea personalizada para calcular su huella de carbono, gracias a un proyecto de la empresa in\u00e8dit y la DO Catalunya. Se trata de una iniciativa pionera dentro de todas las denominaciones de origen del Espa\u00f1a. <strong>El objetivo de este proyecto es \u00abponer a disposici\u00f3n de las bodegas de la DO Catalunya un sistema de medici\u00f3n que les facilite tanto como sea posible el dise\u00f1o de planes de descarbonizaci\u00f3n\u00bb, afirma Carles Gasol, director de Desarrollo de Negocio de in\u00e8dit.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">La herramienta en l\u00ednea que se les proporcionar\u00e1 es la <a href=\"https:\/\/www.edit.management\/index\/\"><strong>\u00e8dit\u00ae<\/strong><\/a>, desarrollada por el estudio de ecoinnovaci\u00f3n estrat\u00e9gica, y permite medir el impacto ambiental de las organizaciones de forma personalizada, continua y autosuficiente, seg\u00fan normativas como la ISO 14064 y la ISO 14046, entre otras. As\u00ed, <strong>in\u00e8dit dise\u00f1ar\u00e1 una \u00e8dit\u00ae preparada para que las bodegas puedan introducir sus datos operativos y de compras, y calcular su huella de carbono.<\/strong> Aunque se les ofrecer\u00e1 apoyo en el c\u00e1lculo de la huella de carbono y en la elaboraci\u00f3n y seguimiento de planes de descarbonizaci\u00f3n, el objetivo es que a largo plazo puedan hacerlo de manera aut\u00f3noma.<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:25px\"><strong>La huella de carbono, un primer paso \u00abimprescindible\u00bb<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">\u00abEl c\u00e1lculo de la huella de carbono de la actividad de una empresa es <strong>el primer paso imprescindible para definir e implementar estrategias de reducci\u00f3n del impacto ambiental y evaluar su efectividad\u00bb, comenta Gasol.<\/strong> Permite conocer el valor absoluto de la contribuci\u00f3n de las bodegas a las emisiones de gases de efecto invernadero, adem\u00e1s de proporcionar conocimiento sobre c\u00f3mo estas emisiones se distribuyen entre las actividades directas e indirectas de las bodegas, como las emitidas por el productor de la energ\u00eda que requiere la bodega, los proveedores y las emitidas por el propio cultivo de la vid. Tambi\u00e9n permite establecer objetivos de reducci\u00f3n y dise\u00f1ar y priorizar acciones efectivas para lograr este prop\u00f3sito. Las acciones para lograr este prop\u00f3sito ser\u00e1n una serie de iniciativas y acciones de reducci\u00f3n de la huella de carbono que se revisar\u00e1n y validar\u00e1n a partir de entrevistas con bodegas de la DO Catalunya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:25px\">La <a href=\"https:\/\/docat.cat\/\">DO Catalunya<\/a>, creada en 1999, agrupa a la gran mayor\u00eda de municipios catalanes productores de vino y actualmente cuenta con 202 bodegas adscritas. Su objetivo es mejorar la calidad de los vinos y de las vi\u00f1as, fomentando la investigaci\u00f3n y la aplicaci\u00f3n de las \u00faltimas tecnolog\u00edas como mecanismos necesarios para dar respuesta a un mercado cada vez m\u00e1s exigente. Actualmente, se comercializan m\u00e1s de sesenta millones de botellas de vino con el sello de la DO Catalunya.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las 202 bodegas catalanas adscritas a la Denominaci\u00f3n de Origen (DO) Catalunya contar\u00e1n pr\u00f3ximamente con una herramienta en l\u00ednea personalizada para calcular su huella de carbono, gracias a un proyecto de la empresa in\u00e8dit y la DO Catalunya. Se trata de una iniciativa pionera dentro de todas las denominaciones de origen del Espa\u00f1a. El objetivo&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/\" title=\"Read Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit\">Read more &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":7201,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43],"tags":[54],"class_list":["post-7207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-metricas","tag-noticia-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit - in\u00e8dit<\/title>\n<meta name=\"description\" content=\"Las 202 bodegas catalanas tendr\u00e1n a su disposici\u00f3n una herramienta online para calcular su huella de carbono gracias a un proyecto con in\u00e8dit\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit - in\u00e8dit\" \/>\n<meta property=\"og:description\" content=\"Las 202 bodegas catalanas tendr\u00e1n a su disposici\u00f3n una herramienta online para calcular su huella de carbono gracias a un proyecto con in\u00e8dit\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/\" \/>\n<meta property=\"og:site_name\" content=\"in\u00e8dit\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ineditinnovacio\/?ref=page_internal\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-28T16:10:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-28T16:19:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ineditinnova.com\/wp-content\/uploads\/2023\/11\/celler_vi-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1706\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Codina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ineditinnova\" \/>\n<meta name=\"twitter:site\" content=\"@ineditinnova\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Codina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/\"},\"author\":{\"name\":\"Codina\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\"},\"headline\":\"Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit\",\"datePublished\":\"2023-11-28T16:10:20+00:00\",\"dateModified\":\"2023-11-28T16:19:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/\"},\"wordCount\":493,\"image\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/celler_vi-scaled.jpg\",\"keywords\":[\"NOTICIA\"],\"articleSection\":[\"CUANTIFICACI\u00d3N DE IMPACTOS AMBIENTALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/\",\"name\":\"Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit - in\u00e8dit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/celler_vi-scaled.jpg\",\"datePublished\":\"2023-11-28T16:10:20+00:00\",\"dateModified\":\"2023-11-28T16:19:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\"},\"description\":\"Las 202 bodegas catalanas tendr\u00e1n a su disposici\u00f3n una herramienta online para calcular su huella de carbono gracias a un proyecto con in\u00e8dit\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/celler_vi-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ineditinnova.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/celler_vi-scaled.jpg\",\"width\":2560,\"height\":1706,\"caption\":\"celler_catalunya\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/\",\"name\":\"in\u00e8dit\",\"description\":\"Dise\u00f1amos soluciones circulares y sostenibles para un futuro mejor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ineditinnova.com\\\/en\\\/#\\\/schema\\\/person\\\/891e1158385858d9972e3d28e2abf5e5\",\"name\":\"Codina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g\",\"caption\":\"Codina\"},\"url\":\"https:\\\/\\\/ineditinnova.com\\\/es\\\/author\\\/inedit\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit - in\u00e8dit","description":"Las 202 bodegas catalanas tendr\u00e1n a su disposici\u00f3n una herramienta online para calcular su huella de carbono gracias a un proyecto con in\u00e8dit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/","og_locale":"es_ES","og_type":"article","og_title":"Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit - in\u00e8dit","og_description":"Las 202 bodegas catalanas tendr\u00e1n a su disposici\u00f3n una herramienta online para calcular su huella de carbono gracias a un proyecto con in\u00e8dit","og_url":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/","og_site_name":"in\u00e8dit","article_publisher":"https:\/\/www.facebook.com\/ineditinnovacio\/?ref=page_internal","article_published_time":"2023-11-28T16:10:20+00:00","article_modified_time":"2023-11-28T16:19:55+00:00","og_image":[{"width":2560,"height":1706,"url":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2023\/11\/celler_vi-scaled.jpg","type":"image\/jpeg"}],"author":"Codina","twitter_card":"summary_large_image","twitter_creator":"@ineditinnova","twitter_site":"@ineditinnova","twitter_misc":{"Escrito por":"Codina","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/#article","isPartOf":{"@id":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/"},"author":{"name":"Codina","@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5"},"headline":"Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit","datePublished":"2023-11-28T16:10:20+00:00","dateModified":"2023-11-28T16:19:55+00:00","mainEntityOfPage":{"@id":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/"},"wordCount":493,"image":{"@id":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/#primaryimage"},"thumbnailUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2023\/11\/celler_vi-scaled.jpg","keywords":["NOTICIA"],"articleSection":["CUANTIFICACI\u00d3N DE IMPACTOS AMBIENTALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/","url":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/","name":"Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit - in\u00e8dit","isPartOf":{"@id":"https:\/\/ineditinnova.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/#primaryimage"},"image":{"@id":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/#primaryimage"},"thumbnailUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2023\/11\/celler_vi-scaled.jpg","datePublished":"2023-11-28T16:10:20+00:00","dateModified":"2023-11-28T16:19:55+00:00","author":{"@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5"},"description":"Las 202 bodegas catalanas tendr\u00e1n a su disposici\u00f3n una herramienta online para calcular su huella de carbono gracias a un proyecto con in\u00e8dit","breadcrumb":{"@id":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/#primaryimage","url":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2023\/11\/celler_vi-scaled.jpg","contentUrl":"https:\/\/ineditinnova.com\/wp-content\/uploads\/2023\/11\/celler_vi-scaled.jpg","width":2560,"height":1706,"caption":"celler_catalunya"},{"@type":"BreadcrumbList","@id":"https:\/\/ineditinnova.com\/es\/els-cellers-de-la-do-catalunya-podran-calcular-petjada-carboni-gracies-a-projecte-amb-inedit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/ineditinnova.com\/es\/"},{"@type":"ListItem","position":2,"name":"Las bodegas de la DO Catalunya podr\u00e1n calcular su huella de carbono gracias a una herramienta desarrollada por in\u00e8dit"}]},{"@type":"WebSite","@id":"https:\/\/ineditinnova.com\/en\/#website","url":"https:\/\/ineditinnova.com\/en\/","name":"in\u00e8dit","description":"Dise\u00f1amos soluciones circulares y sostenibles para un futuro mejor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ineditinnova.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/ineditinnova.com\/en\/#\/schema\/person\/891e1158385858d9972e3d28e2abf5e5","name":"Codina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4fff7c6f6d19e46cfd6c15f0f9b4aeb9970dd1aa4028caf6584e34d95cb8a41d?s=96&d=mm&r=g","caption":"Codina"},"url":"https:\/\/ineditinnova.com\/es\/author\/inedit\/"}]}},"_links":{"self":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/7207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/comments?post=7207"}],"version-history":[{"count":4,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/7207\/revisions"}],"predecessor-version":[{"id":7213,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/posts\/7207\/revisions\/7213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/media\/7201"}],"wp:attachment":[{"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/media?parent=7207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/categories?post=7207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ineditinnova.com\/es\/wp-json\/wp\/v2\/tags?post=7207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}